{"id":44,"date":"2019-05-11T15:03:07","date_gmt":"2019-05-11T15:03:07","guid":{"rendered":"https:\/\/pixxen.de\/?page_id=44"},"modified":"2019-05-11T15:03:29","modified_gmt":"2019-05-11T15:03:29","slug":"cookie-richtlinie","status":"publish","type":"page","link":"https:\/\/pixxen.de\/index.php\/info\/cookie-richtlinie\/","title":{"rendered":"Cookie-Richtlinie"},"content":{"rendered":"\n<!-- Legal document generated by Complianz | GDPR\/CCPA Cookie Consent https:\/\/wordpress.org\/plugins\/complianz-gdpr -->\n<div id=\"cmplz-document\" class=\"cmplz-document cookie-statement cmplz-document-eu\"><p><i>Diese Cookie-Richtlinie wurde zuletzt am 17. Juni 2024 aktualisiert und gilt f\u00fcr B\u00fcrger und Einwohner mit st\u00e4ndigem Wohnsitz im Europ\u00e4ischen Wirtschaftsraum und der Schweiz.<\/i><br><\/p><h2>1. Einf\u00fchrung<\/h2><p>Unsere Website, <a href=\"https:\/\/pixxen.de\">https:\/\/pixxen.de<\/a> (im folgenden: &#8222;Die Website&#8220;) verwendet Cookies und \u00e4hnliche Technologien (der Einfachheit halber werden all diese unter &#8222;Cookies&#8220; zusammengefasst). Cookies werden au\u00dferdem von uns beauftragten Drittparteien platziert. In dem unten stehendem Dokument informieren wir dich \u00fcber die Verwendung von Cookies auf unserer Website.<\/p><h2>2. Was sind Cookies?<\/h2><p>Ein Cookie ist eine einfache kleine Datei, die gemeinsam mit den Seiten einer Internetadresse versendet und vom Webbrowser auf dem PC oder einem anderen Ger\u00e4t gespeichert werden kann. Die darin gespeicherten Informationen k\u00f6nnen w\u00e4hrend folgender Besuche zu unseren oder den Servern relevanter Drittanbieter gesendet werden.<\/p><h2>3. Was sind Skripte?<\/h2><p>Ein Script ist ein St\u00fcck Programmcode, das benutzt wird, um unserer Website Funktionalit\u00e4t und Interaktivit\u00e4t zu erm\u00f6glichen. Dieser Code wird auf unseren Servern oder auf deinem Ger\u00e4t ausgef\u00fchrt.<\/p><h2>4. Was ist ein Web Beacon?<\/h2><p>Ein Web-Beacon (auch Pixel-Tag genannt), ist ein kleines unsichtbares Textfragment oder Bild auf einer Website, das benutzt wird, um den Verkehr auf der Website zu \u00fcberwachen. Um dies zu erm\u00f6glichen werden diverse Daten von dir mittels Web-Beacons gespeichert.<\/p><h2>5. Cookies<\/h2><p class=\"cmplz-subtitle\">5.1 Technische oder funktionelle Cookies<\/p><p>Einige Cookies stellen sicher, dass Teile unserer Website richtig funktionieren und deine Nutzervorlieben bekannt bleiben. Durch das Platzieren funktionaler Cookies machen wir es dir einfacher unsere Website zu besuchen. Auf diese Weise musst du bei Besuchen unserer Website nicht wiederholt die gleichen Informationen eingeben, oder deine Gegenst\u00e4nde bleiben beispielsweise in deinem Warenkorb bis du bezahlst. Wir k\u00f6nnen diese Cookies ohne dein Einverst\u00e4ndnis platzieren.<\/p><p class=\"cmplz-subtitle\">5.2 Analytische Cookies<\/p><p>Wir verwenden analytische Cookies, um das Website-Erlebnis f\u00fcr unsere Nutzer zu optimieren. Mit diesen analytischen Cookies erhalten wir Einblicke in die Nutzung unserer Website.&nbsp;Wir bitten um deine Erlaubnis, analytische Cookies zu setzen.<\/p><p class=\"cmplz-subtitle\">5.3 Marketing- \/ Tracking-Cookies<\/p><p>Marketing- \/ Tracking-Cookies sind Cookies oder eine andere Form der lokalen Speicherung, die zur Erstellung von Benutzerprofilen verwendet werden, um Werbung anzuzeigen oder den Benutzer auf dieser Website oder \u00fcber mehrere Websites hinweg f\u00fcr \u00e4hnliche Marketingzwecke zu verfolgen.<\/p><p class=\"cmplz-subtitle\">5.4 Soziale-Medien<\/p><p>Auf unserer Website haben wir Inhalte von Instagram eingebunden, um Webseiten zu bewerben (z. B. &#8222;Gef\u00e4llt mir&#8220;, &#8222;Pin&#8220;) oder zu teilen (z. B. &#8222;Tweet&#8220;) in sozialen Netzwerken wie Instagram. Dieser Inhalt ist mit Code eingebettet, der von Instagram stammt und Cookies platziert. Diese Inhalte k\u00f6nnen bestimmte Informationen f\u00fcr personalisierte Werbung speichern und verarbeiten.<\/p><p>Bitte lies die Datenschutzerkl\u00e4rung dieser sozialen Netzwerke (die sich regelm\u00e4\u00dfig \u00e4ndern kann), um zu erfahren, wie sie mit deinen (pers\u00f6nlichen) Daten umgehen, die sie mithilfe dieser Cookies verarbeiten. Die abgerufenen Daten werden so weit wie m\u00f6glich anonymisiert. Instagram hat seinen Sitz in den Vereinigten Staaten<\/p><h2>6. Platzierte Cookies<\/h2><div id=\"cmplz-cookies-overview\"><details class=\"cmplz-dropdown cmplz-service-desc cmplz-dropdown-cookiepolicy \">\n\t<summary class=\"cmplz-service-header\"><div>\n\t\t<h3>Sonstiges<\/h3>\n\t\t<p>Gegenstand der Untersuchung<\/p>\n\t\t<label for=\"cmplz_service_sonstiges\" class=\"cmplz_consent_per_service_label\"><span class=\"screen-reader-text\">Consent to service sonstiges<\/span><\/label>\n\t\t<input type=\"checkbox\" id=\"cmplz_service_sonstiges\" class=\"cmplz-accept-service cmplz-hidden\" data-service=\"sonstiges\" data-category=\"functional\"><\/div>\n\t<\/summary>\n\t<div class=\"cmplz-service-description\">\n\t\t<h4>Nutzung<\/h4>\n\t\t<p><\/p>\n\t<\/div>\n\t<div class=\"cmplz-sharing-data\">\n\t\t<h4>Weitergabe von Daten<\/h4>\n\t\t<p>Die Weitergabe von Daten wird noch untersucht<\/p>\n\t<\/div>\n\t<div class=\"cookies-per-purpose\">\n    <div class=\"purpose\"><h4>Gegenstand der Untersuchung<\/h4><\/div>\n    <div class=\"name-header\">\n\t<h5>Name<\/h5>\n<\/div>\n<div class=\"name\">cmplz_consenttype<\/div>\n<div class=\"retention-header\">\n\t<h5>Ablaufdatum<\/h5>\n<\/div>\n<div class=\"retention\">365 Tage<\/div>\n<div class=\"function-header\">\n\t<h5>Funktion<\/h5>\n<\/div>\n<div class=\"function\"><\/div>\n<div class=\"name-header\">\n\t<h5>Name<\/h5>\n<\/div>\n<div class=\"name\">_ym_synced<\/div>\n<div class=\"retention-header\">\n\t<h5>Ablaufdatum<\/h5>\n<\/div>\n<div class=\"retention\"><\/div>\n<div class=\"function-header\">\n\t<h5>Funktion<\/h5>\n<\/div>\n<div class=\"function\"><\/div>\n<div class=\"name-header\">\n\t<h5>Name<\/h5>\n<\/div>\n<div class=\"name\">_ym_wv2rf:96508558:0<\/div>\n<div class=\"retention-header\">\n\t<h5>Ablaufdatum<\/h5>\n<\/div>\n<div class=\"retention\"><\/div>\n<div class=\"function-header\">\n\t<h5>Funktion<\/h5>\n<\/div>\n<div class=\"function\"><\/div>\n<div class=\"name-header\">\n\t<h5>Name<\/h5>\n<\/div>\n<div class=\"name\">_ym_uid<\/div>\n<div class=\"retention-header\">\n\t<h5>Ablaufdatum<\/h5>\n<\/div>\n<div class=\"retention\"><\/div>\n<div class=\"function-header\">\n\t<h5>Funktion<\/h5>\n<\/div>\n<div class=\"function\"><\/div>\n<div class=\"name-header\">\n\t<h5>Name<\/h5>\n<\/div>\n<div class=\"name\">WP_DATA_USER_2<\/div>\n<div class=\"retention-header\">\n\t<h5>Ablaufdatum<\/h5>\n<\/div>\n<div class=\"retention\"><\/div>\n<div class=\"function-header\">\n\t<h5>Funktion<\/h5>\n<\/div>\n<div class=\"function\"><\/div>\n<div class=\"name-header\">\n\t<h5>Name<\/h5>\n<\/div>\n<div class=\"name\">_ym96508558:0_reqNum<\/div>\n<div class=\"retention-header\">\n\t<h5>Ablaufdatum<\/h5>\n<\/div>\n<div class=\"retention\"><\/div>\n<div class=\"function-header\">\n\t<h5>Funktion<\/h5>\n<\/div>\n<div class=\"function\"><\/div>\n<div class=\"name-header\">\n\t<h5>Name<\/h5>\n<\/div>\n<div class=\"name\">_ym96508558_lsid<\/div>\n<div class=\"retention-header\">\n\t<h5>Ablaufdatum<\/h5>\n<\/div>\n<div class=\"retention\"><\/div>\n<div class=\"function-header\">\n\t<h5>Funktion<\/h5>\n<\/div>\n<div class=\"function\"><\/div>\n<div class=\"name-header\">\n\t<h5>Name<\/h5>\n<\/div>\n<div class=\"name\">_ym_retryReqs<\/div>\n<div class=\"retention-header\">\n\t<h5>Ablaufdatum<\/h5>\n<\/div>\n<div class=\"retention\"><\/div>\n<div class=\"function-header\">\n\t<h5>Funktion<\/h5>\n<\/div>\n<div class=\"function\"><\/div>\n<div class=\"name-header\">\n\t<h5>Name<\/h5>\n<\/div>\n<div class=\"name\">wpgmza-api-consent-given<\/div>\n<div class=\"retention-header\">\n\t<h5>Ablaufdatum<\/h5>\n<\/div>\n<div class=\"retention\"><\/div>\n<div class=\"function-header\">\n\t<h5>Funktion<\/h5>\n<\/div>\n<div class=\"function\"><\/div>\n<div class=\"name-header\">\n\t<h5>Name<\/h5>\n<\/div>\n<div class=\"name\">_pk_id.8.47de<\/div>\n<div class=\"retention-header\">\n\t<h5>Ablaufdatum<\/h5>\n<\/div>\n<div class=\"retention\"><\/div>\n<div class=\"function-header\">\n\t<h5>Funktion<\/h5>\n<\/div>\n<div class=\"function\"><\/div>\n<div class=\"name-header\">\n\t<h5>Name<\/h5>\n<\/div>\n<div class=\"name\">_ym_d<\/div>\n<div class=\"retention-header\">\n\t<h5>Ablaufdatum<\/h5>\n<\/div>\n<div class=\"retention\"><\/div>\n<div class=\"function-header\">\n\t<h5>Funktion<\/h5>\n<\/div>\n<div class=\"function\"><\/div>\n<div class=\"name-header\">\n\t<h5>Name<\/h5>\n<\/div>\n<div class=\"name\">tk_ai<\/div>\n<div class=\"retention-header\">\n\t<h5>Ablaufdatum<\/h5>\n<\/div>\n<div class=\"retention\"><\/div>\n<div class=\"function-header\">\n\t<h5>Funktion<\/h5>\n<\/div>\n<div class=\"function\"><\/div>\n<div class=\"name-header\">\n\t<h5>Name<\/h5>\n<\/div>\n<div class=\"name\">cmplz_policy_id<\/div>\n<div class=\"retention-header\">\n\t<h5>Ablaufdatum<\/h5>\n<\/div>\n<div class=\"retention\">365 Tage<\/div>\n<div class=\"function-header\">\n\t<h5>Funktion<\/h5>\n<\/div>\n<div class=\"function\"><\/div>\n<div class=\"name-header\">\n\t<h5>Name<\/h5>\n<\/div>\n<div class=\"name\">cmplz_consented_services<\/div>\n<div class=\"retention-header\">\n\t<h5>Ablaufdatum<\/h5>\n<\/div>\n<div class=\"retention\">365 Tage<\/div>\n<div class=\"function-header\">\n\t<h5>Funktion<\/h5>\n<\/div>\n<div class=\"function\"><\/div>\n<div class=\"name-header\">\n\t<h5>Name<\/h5>\n<\/div>\n<div class=\"name\">cmplz_marketing<\/div>\n<div class=\"retention-header\">\n\t<h5>Ablaufdatum<\/h5>\n<\/div>\n<div class=\"retention\">365 Tage<\/div>\n<div class=\"function-header\">\n\t<h5>Funktion<\/h5>\n<\/div>\n<div class=\"function\"><\/div>\n<div class=\"name-header\">\n\t<h5>Name<\/h5>\n<\/div>\n<div class=\"name\">cmplz_statistics<\/div>\n<div class=\"retention-header\">\n\t<h5>Ablaufdatum<\/h5>\n<\/div>\n<div class=\"retention\">365 Tage<\/div>\n<div class=\"function-header\">\n\t<h5>Funktion<\/h5>\n<\/div>\n<div class=\"function\"><\/div>\n<div class=\"name-header\">\n\t<h5>Name<\/h5>\n<\/div>\n<div class=\"name\">cmplz_preferences<\/div>\n<div class=\"retention-header\">\n\t<h5>Ablaufdatum<\/h5>\n<\/div>\n<div class=\"retention\">365 Tage<\/div>\n<div class=\"function-header\">\n\t<h5>Funktion<\/h5>\n<\/div>\n<div class=\"function\"><\/div>\n<div class=\"name-header\">\n\t<h5>Name<\/h5>\n<\/div>\n<div class=\"name\">cmplz_functional<\/div>\n<div class=\"retention-header\">\n\t<h5>Ablaufdatum<\/h5>\n<\/div>\n<div class=\"retention\">365 Tage<\/div>\n<div class=\"function-header\">\n\t<h5>Funktion<\/h5>\n<\/div>\n<div class=\"function\"><\/div>\n<div class=\"name-header\">\n\t<h5>Name<\/h5>\n<\/div>\n<div class=\"name\">cmplz_banner-status<\/div>\n<div class=\"retention-header\">\n\t<h5>Ablaufdatum<\/h5>\n<\/div>\n<div class=\"retention\">365 Tage<\/div>\n<div class=\"function-header\">\n\t<h5>Funktion<\/h5>\n<\/div>\n<div class=\"function\"><\/div>\n<div class=\"name-header\">\n\t<h5>Name<\/h5>\n<\/div>\n<div class=\"name\">wp-settings-time-2<\/div>\n<div class=\"retention-header\">\n\t<h5>Ablaufdatum<\/h5>\n<\/div>\n<div class=\"retention\"><\/div>\n<div class=\"function-header\">\n\t<h5>Funktion<\/h5>\n<\/div>\n<div class=\"function\"><\/div>\n<div class=\"name-header\">\n\t<h5>Name<\/h5>\n<\/div>\n<div class=\"name\">wp-settings-2<\/div>\n<div class=\"retention-header\">\n\t<h5>Ablaufdatum<\/h5>\n<\/div>\n<div class=\"retention\"><\/div>\n<div class=\"function-header\">\n\t<h5>Funktion<\/h5>\n<\/div>\n<div class=\"function\"><\/div>\n<div class=\"name-header\">\n\t<h5>Name<\/h5>\n<\/div>\n<div class=\"name\">wordpress_test_cookie<\/div>\n<div class=\"retention-header\">\n\t<h5>Ablaufdatum<\/h5>\n<\/div>\n<div class=\"retention\"><\/div>\n<div class=\"function-header\">\n\t<h5>Funktion<\/h5>\n<\/div>\n<div class=\"function\"><\/div>\n<div class=\"name-header\">\n\t<h5>Name<\/h5>\n<\/div>\n<div class=\"name\">_pk_id_8_47de<\/div>\n<div class=\"retention-header\">\n\t<h5>Ablaufdatum<\/h5>\n<\/div>\n<div class=\"retention\"><\/div>\n<div class=\"function-header\">\n\t<h5>Funktion<\/h5>\n<\/div>\n<div class=\"function\"><\/div>\n<div class=\"name-header\">\n\t<h5>Name<\/h5>\n<\/div>\n<div class=\"name\">wordpress_logged_in_0a512e38a3dd497be31f10b89cc06772<\/div>\n<div class=\"retention-header\">\n\t<h5>Ablaufdatum<\/h5>\n<\/div>\n<div class=\"retention\"><\/div>\n<div class=\"function-header\">\n\t<h5>Funktion<\/h5>\n<\/div>\n<div class=\"function\"><\/div>\n<div class=\"name-header\">\n\t<h5>Name<\/h5>\n<\/div>\n<div class=\"name\">WP_DATA_USER_3<\/div>\n<div class=\"retention-header\">\n\t<h5>Ablaufdatum<\/h5>\n<\/div>\n<div class=\"retention\"><\/div>\n<div class=\"function-header\">\n\t<h5>Funktion<\/h5>\n<\/div>\n<div class=\"function\"><\/div>\n<div class=\"name-header\">\n\t<h5>Name<\/h5>\n<\/div>\n<div class=\"name\">wp-settings-3<\/div>\n<div class=\"retention-header\">\n\t<h5>Ablaufdatum<\/h5>\n<\/div>\n<div class=\"retention\"><\/div>\n<div class=\"function-header\">\n\t<h5>Funktion<\/h5>\n<\/div>\n<div class=\"function\"><\/div>\n<div class=\"name-header\">\n\t<h5>Name<\/h5>\n<\/div>\n<div class=\"name\">wp-settings-time-3<\/div>\n<div class=\"retention-header\">\n\t<h5>Ablaufdatum<\/h5>\n<\/div>\n<div class=\"retention\"><\/div>\n<div class=\"function-header\">\n\t<h5>Funktion<\/h5>\n<\/div>\n<div class=\"function\"><\/div>\n<div class=\"name-header\">\n\t<h5>Name<\/h5>\n<\/div>\n<div class=\"name\">ucp_tabs<\/div>\n<div class=\"retention-header\">\n\t<h5>Ablaufdatum<\/h5>\n<\/div>\n<div class=\"retention\"><\/div>\n<div class=\"function-header\">\n\t<h5>Funktion<\/h5>\n<\/div>\n<div class=\"function\"><\/div>\n\n<\/div>\n<\/details>\n<\/div><h2>7. Zustimmung<\/h2><p>Wenn du unsere Website das erste Mal besuchst, zeigen wir dir ein Pop-Up mit einer Erkl\u00e4rung \u00fcber Cookies. Sobald du auf &#8222;Alle Cookies&#8220; klickst, gibst du uns dein Einverst\u00e4ndnis alle in diesem Pop-Up und in der Cookie-Richtlinie beschriebenen Cookies und Plugins zu verwenden. Du kannst die Verwendung von Cookies \u00fcber deinen Browser deaktivieren, aber bitte beachte, dass unsere Website dann unter Umst\u00e4nden nicht richtig funktioniert.<\/p><p class=\"cmplz-subtitle\">7.1 Verwalte deine Zustimmungseinstellungen<\/p><div id=\"cmplz-manage-consent-container-nojavascript\">Du hast die Cookie-Richtlinie ohne Javascript-Unterst\u00fctzung geladen.&nbsp;Unter AMP kannst du die Schaltfl\u00e4che zum Zustimmen der Einwilligung unten auf der Seite verwenden.<\/div><div id=\"cmplz-manage-consent-container\" name=\"cmplz-manage-consent-container\" class=\"cmplz-manage-consent-container\"><\/div><h2>8. Aktivierung\/Deaktivierung und L\u00f6schen von Cookies<\/h2><p>Du kannst deinen Internetbrowser verwenden um automatisch oder manuell Cookies zu l\u00f6schen. Du kannst au\u00dferdem spezifizieren ob spezielle Cookies nicht platziert werden sollen. Eine andere M\u00f6glichkeit ist es deinen  Internetbrowser derart einzurichten, dass du jedes Mal benachrichtigt wirst, wenn ein Cookie platziert wird. F\u00fcr weitere Information \u00fcber diese M\u00f6glichkeiten beachte die Anweisungen in der Hilfesektion deines Browsers.<\/p><p>Bitte nimm zur Kentniss, dass unsere Website m\u00f6glicherweise nicht richtig funktioniert wenn alle Cookies deaktiviert sind. Wenn du die Cookies in deinem Browser l\u00f6scht, werden diese neuplatziert wenn du unsere Website erneut besuchst.<\/p><h2>9. Deine Rechte in Bezug auf pers\u00f6nliche Daten<\/h2><p>Du hast in Bezug auf deine pers\u00f6nlichen Daten die folgenden Rechte:<\/p><ul>\n                    <li>Du hast das Recht zu wissen, warum deine pers\u00f6nlichen Daten gebraucht werden, was mit ihnen passiert und wie lange diese verwahrt werden.<\/li>\n                    <li>Zugriffsrecht: Du hast das Recht deine uns bekannten pers\u00f6nliche Daten einzusehen.<\/li>\n                    <li>Recht auf Berichtigung: Du hast das Recht wann immer du w\u00fcnscht, deine pers\u00f6nlichen Daten zu erg\u00e4nzen, zu korrigieren sowie gel\u00f6scht oder blockiert zu bekommen.<\/li>\n                    <li>Wenn du uns dein Einverst\u00e4ndnis zur Verarbeitung deiner Daten gegeben hast, hast du das Recht dieses Einverst\u00e4ndnis zu widerrufen und deine pers\u00f6nlichen Daten l\u00f6schen zu lassen.<\/li>\n                    <li>Recht auf Datentransfer deiner Daten: Du hast das Recht, alle deine pers\u00f6nlichen Daten von einem Kontrolleur anzufordern und in ihrer Gesamtheit zu einem anderen Kontrolleur zu transferieren.<\/li>\n                    <li>Widerspruchsrecht: Du kannst der Verarbeitung deiner Daten widersprechen. Wir entsprechen dem, es sei denn es gibt berechtigte Gr\u00fcnde f\u00fcr die Verarbeitung.<\/li>\n                <\/ul><p>Um diese Rechte auszu\u00fcben kontaktiere uns bitte. Bitte beziehe dich auf die Kontaktdaten am Ende dieser Cookie-Erkl\u00e4rung. Wenn du eine Beschwerde dar\u00fcber hast, wie wir deine Daten behandeln, w\u00fcrden wir diese gerne h\u00f6ren, aber du hast auch das Recht diese an die Aufsichtsbeh\u00f6rde (der Datenschutzbeh\u00f6rde) zu richten.<\/p><h2>10. Kontaktdaten<\/h2><p>F\u00fcr Fragen und\/oder Kommentare \u00fcber unsere Cookie-Richtlinien und diese Aussage kontaktiere uns bitte mittels der folgenden Kontaktdaten:<\/p><p><span class=\"cmplz-contact-organisation\">Pixxen e.V.<\/span><br>\n                      <span class=\"cmplz-contact-address\"> Pixxen e.V., Neukamperfehn <\/span><br>\n                      <span class=\"cmplz-contact-country\">Deutschland<\/span><br>\n                    Website: <span class=\"cmplz-contact-domain\"><a href=\"https:\/\/pixxen.de\">https:\/\/pixxen.de<\/a><\/span><br>\n                    E-Mail: <span class=\"cmplz-contact-email\"><span class=\"cmplz-obfuscate\">ed&#046;nexxip&#x40;ztu&#x68;csne&#116;ad<\/span><\/span><br>\n                    <span class=\"cmplz-contact-telephone\"><\/span><\/p><p>Diese Cookie-Richtlinie wurde mit <a href=\"https:\/\/cookiedatabase.org\/\" target=\"_blank\">cookiedatabase.org<\/a> am 30. Dezember 2019 synchronisiert.<\/p><\/div>","protected":false},"excerpt":{"rendered":"","protected":false},"author":1,"featured_media":0,"parent":42,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":[],"_links":{"self":[{"href":"https:\/\/pixxen.de\/index.php\/wp-json\/wp\/v2\/pages\/44"}],"collection":[{"href":"https:\/\/pixxen.de\/index.php\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/pixxen.de\/index.php\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/pixxen.de\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/pixxen.de\/index.php\/wp-json\/wp\/v2\/comments?post=44"}],"version-history":[{"count":1,"href":"https:\/\/pixxen.de\/index.php\/wp-json\/wp\/v2\/pages\/44\/revisions"}],"predecessor-version":[{"id":45,"href":"https:\/\/pixxen.de\/index.php\/wp-json\/wp\/v2\/pages\/44\/revisions\/45"}],"up":[{"embeddable":true,"href":"https:\/\/pixxen.de\/index.php\/wp-json\/wp\/v2\/pages\/42"}],"wp:attachment":[{"href":"https:\/\/pixxen.de\/index.php\/wp-json\/wp\/v2\/media?parent=44"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}