{"id":6779,"date":"2026-09-01T08:56:07","date_gmt":"2026-09-01T08:56:07","guid":{"rendered":"https:\/\/pixxen.de\/?p=6779"},"modified":"2026-09-01T08:56:08","modified_gmt":"2026-09-01T08:56:08","slug":"danke-3","status":"publish","type":"post","link":"https:\/\/pixxen.de\/index.php\/2026\/09\/01\/danke-3\/","title":{"rendered":"Danke!"},"content":{"rendered":"\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" width=\"789\" height=\"983\" src=\"https:\/\/pixxen.de\/wp-content\/uploads\/2026\/09\/787046609_1773632010641433_3620578615413364915_n.jpg\" alt=\"\" class=\"wp-image-6780\" srcset=\"https:\/\/pixxen.de\/wp-content\/uploads\/2026\/09\/787046609_1773632010641433_3620578615413364915_n.jpg 789w, https:\/\/pixxen.de\/wp-content\/uploads\/2026\/09\/787046609_1773632010641433_3620578615413364915_n-241x300.jpg 241w, https:\/\/pixxen.de\/wp-content\/uploads\/2026\/09\/787046609_1773632010641433_3620578615413364915_n-768x957.jpg 768w\" sizes=\"(max-width: 767px) 89vw, (max-width: 1000px) 54vw, (max-width: 1071px) 543px, 580px\" \/><\/figure>\n\n\n\n<p>N\u00e4chstes Jahr gehts am 28.08 in die 17. Runde \ud83d\ude09<\/p>\n\n\n\n<p>Weitere Infos zu Spendensumme, Bildern, Aftermovie folgen hier im Laufe der Zeit!<\/p>\n","protected":false},"excerpt":{"rendered":"<p>N\u00e4chstes Jahr gehts am 28.08 in die 17. Runde \ud83d\ude09 Weitere Infos zu Spendensumme, Bildern, Aftermovie folgen hier im Laufe der Zeit!<\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[11],"tags":[],"_links":{"self":[{"href":"https:\/\/pixxen.de\/index.php\/wp-json\/wp\/v2\/posts\/6779"}],"collection":[{"href":"https:\/\/pixxen.de\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/pixxen.de\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/pixxen.de\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/pixxen.de\/index.php\/wp-json\/wp\/v2\/comments?post=6779"}],"version-history":[{"count":1,"href":"https:\/\/pixxen.de\/index.php\/wp-json\/wp\/v2\/posts\/6779\/revisions"}],"predecessor-version":[{"id":6781,"href":"https:\/\/pixxen.de\/index.php\/wp-json\/wp\/v2\/posts\/6779\/revisions\/6781"}],"wp:attachment":[{"href":"https:\/\/pixxen.de\/index.php\/wp-json\/wp\/v2\/media?parent=6779"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/pixxen.de\/index.php\/wp-json\/wp\/v2\/categories?post=6779"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/pixxen.de\/index.php\/wp-json\/wp\/v2\/tags?post=6779"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}